{"id":100,"date":"2015-10-02T00:00:00","date_gmt":"2015-10-01T22:00:00","guid":{"rendered":"https:\/\/www.romanews.it\/blog\/index.php\/2015\/10\/02\/economia-solidale-conosciamola-con-i-fumetti\/"},"modified":"2017-10-09T04:16:05","modified_gmt":"2017-10-09T02:16:05","slug":"economia-solidale-conosciamola-con-i-fumetti","status":"publish","type":"post","link":"https:\/\/www.romanews.it\/blog\/economia-solidale-conosciamola-con-i-fumetti\/","title":{"rendered":"Economia solidale&#8230; conosciamola con i fumetti!"},"content":{"rendered":"<p>Noi, del blog di romanews.it, ci teniamo \u00a0a scrivere contenuti originali e assolutamente NON copiati ma, proponendo una sezione WIKI dedicata all&#8217;economia solidale ed ai GAS (gruppi di acquisto solidale),\u00a0siamo rimasti conquistati dalla descrizione in chiave &#8220;cartoons&#8221; fatta da Topolino nel 2011 magistralmente descritta dal blog<br \/>\n<a href=\"https:\/\/fumettologicamente.wordpress.com\/tag\/topolino\/page\/3\/\" target=\"_blank\" rel=\"noopener\">https:\/\/fumettologicamente.wordpress.com\/tag\/topolino\/page\/3\/<\/a><br \/>\nVi proponiamo quindi, in modalit\u00e0\u00a0&#8220;RASSEGNA STAMPA&#8221;, l&#8217;articolo pubblicato alla URL indicata:<\/p>\n<p>&nbsp;<\/p>\n<pre>Il businessbuonismo di Paperone, e la pedagogia economica\r\nPosted on 18\/10\/2011 by matteos<\/pre>\n<p>&nbsp;<\/p>\n<p>In uno degli ultimi numeri (2913), Topolino apriva con la storia <em>Zio Paperone e la campagna in citt\u00e0<\/em> (testi Marco Bosco, disegni Marco Mazzarello).<br \/>\nMi \u00e8 parsa una storia pi\u00f9 interessante del solito. Ma non tanto perch\u00e9 era dedicata al tema attuale del cibo biologico. Come sapete, che Topolino produca storie ispirate all\u2019attualit\u00e0 \u2013 dai fatti puntuali ai temi nell\u2019agenda dei media \u2013 non \u00e8 una novit\u00e0. E che questa abitudine sia anche una leva di marketing per il settimanale, \u00e8 pure cosa nota. Infine, che l\u2019ecologia sia un tema da tempo presente nelle storie Disney italiane, e che questo sia attraversato da ampie dosi di buonismo, \u00e8 altrettanto evidente arcinoto. Basti pensare a un anno fa, quando Topolino 2834 ospit\u00f2 la storia <em>Paperinik e il mistero a impatto zero<\/em>, sul tema delle emissioni di co2.<\/p>\n<p>Per precisione, dunque: nel numero in questione, la cui copertina portava lo strillo \u201cnumero speciale Topogreen\u201d, il tema ecologico era declinato anche come strumento di marketing, per accompagnare la decisione (argomentata anche nell\u2019editoriale dalla direttrice) di iniziare a stampare il giornale su carta riciclata con certificato PFEC.<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino1s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-853 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino1s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"632\" \/><\/a><\/p>\n<p>Sbrigate le premesse, gli aspetti che mi sono parsi interessanti sono questi:<\/p>\n<p>1- Il primo \u00e8 quello pi\u00f9 evidente: il tema del cibo biologico \u00e8 affrontato attraverso una chiave di lettura che non \u00e8 solo valoriale. Non si tratta di una generica catechesi ecologista, del tipo \u201cci\u00f2 che rispetta la natura \u00e8 cosa buona in s\u00e9. Punto\u201d. La lettura immaginata da redazione e autori \u00e8 invece economica: il biologico come *modello differente* nella produzione e mercato dell\u2019alimentazione. Al centro non c\u2019\u00e8 il valore del BIO in s\u00e9, ma il valore specifico della <em>filiera corta<\/em>.<\/p>\n<p>La storia si apre con un canonico shock imprenditoriale di Paperone, disperato per il declino delle vendite di frutta e verdura coltivate (e commercializzate) dalle sue imprese del settore. La ragione \u00e8 che i consumatori sembrano avere cambiato le loro abitudini di acquisto, abbandonando i supermarket P.d.P per il nuovo \u201cMercato dei contadini\u201d:<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino2s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-854 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino2s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"640\" \/><\/a><a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino3s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-855 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino3s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"644\" \/><\/a><\/p>\n<p>In questa rappresentazione, Nonna Papera incarna la filiera corta, mentre Paperone \u00e8 il simbolo dell\u2019agricoltura industrale. Una trovata sensata e brillante, perch\u00e9 \u00e8 perfettamente giustificata dall\u2019identit\u00e0 dei personaggi, ma al contempo ne offre una specie di rilettura alternativa e\/o aggiornata, che sovrappone il tema odierno agli stili di vita tradizionalmente diversi dei due paperi. Il cibo di Nonna Papera, proverbialmente \u201cpi\u00f9 buono\u201d, si rivela tale non solo grazie alle sue abilit\u00e0 in cucina, e non \u00e8 semplicemente \u2018genuino\u2019: proviene da un altro <strong>modello di produzione agricola<\/strong>. La <a href=\"http:\/\/www.reggio-emilia.coldiretti.it\/il-kmzero-conquista-anche-topolino-.aspx?KeyPub=GP_CD_REGGIOEMILIA_HOME%7CCD_REGGIOEMILIA_HOME&amp;Cod_Oggetto=30142506&amp;subskintype=Detail\" target=\"_blank\" rel=\"noopener\">Coldiretti <\/a>sembra avere apprezzato.<\/p>\n<p>2- Da qui viene un secondo aspetto che mi pare ancora pi\u00f9 interessante. La narrazione non si limita a mettere in scena una sorta di invenzione o scoperta. Non si ferma alla descrizione di una eccentrica (esotica, fantasiosa, eccezionale) diversit\u00e0, ma la rappresenta in azione nel \u2018normale\u2019 contesto paperopolese, ovvero di una citt\u00e0 i cui modelli di produzione imperanti sono altri, e in cui i principali imprenditori (Paperone e Rockerduck) non sono disposti a farsi facilmente bypassare. <em>Zio Paperone e la campagna in citt\u00e0<\/em> prova quindi a mettere in scena il <strong>conflitto tra diversi modelli economici<\/strong>: quello dei contadini organizzati, e quello degli industriali dell\u2019agricoltura.<\/p>\n<p>La storia racconta quindi la reazione di Paperone, imprenditore in crisi che decide di cambiare strategia, affrontando la nuova concorrenza sullo stesso terreno: la vecchia tuba si lancia nella produzione di cibo biologico. Un percorso cui non mancano gli ostacoli. Dapprima cerca di acquistare qualche terreno agricolo; ma non ne trova disponibili (e anzi una sua offerta \u00e8 respinta a pallettoni da Dinamite Bla). In seguito cerca una soluzione diversa, per certi versi coraggiosa e inventiva: attraverso la riqualificazione di una antica miniera di carbone sepolta sotto al centro di Paperopoli, arriva a realizzare \u201cUnderland P.d.P.\u201d, la prima azienda ortofrutticola sotterranea:<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino4s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-856 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino4s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"589\" height=\"800\" \/><\/a><a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino5s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-857 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino5s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"634\" \/><\/a><\/p>\n<p>L\u2019operazione \u00e8 un successo: prodotti di qualit\u00e0, in grandi quantit\u00e0 \u2013 dunque a prezzi bassi \u2013 e in un contesto che per i clienti \u00e8 anche un piacere \u2018divertente\u2019 (la surreale idea dello shopping-raccolta diretta dalle piante). E questo successo mette presto in crisi il \u201cmercato dei contadini\u201d. In uno scambio di vedute con i nipotini, preoccupati anche per Nonna Papera, il capitalista Paperone teorizza:<\/p>\n<blockquote><p><em>la libera concorrenza ha le sue leggi! A volte sono dure, ma vanno rispettate! Entrando nel mercato, i contadini se ne sono assunti il rischio!<\/em><\/p><\/blockquote>\n<p>Gi\u00e0, il mercato premia chi rischia e innova, e lo zione prospera. Al punto che il concorrente Rockerduck (il cui analogo business \u2018tradizionale\u2019 \u00e8 anch\u2019esso in crisi) non pu\u00f2 restare a guardare. Ecco dunque entrare in scena l\u2019antico rivale, che \u2018copia\u2019 il concorrente con un\u2019iniziativa non da meno: un\u2019azienda ortofrutticola subacquea, ancora pi\u00f9 vasta e spettacolare. Risultato: un successo che spiazza lo stesso Paperone.<\/p>\n<p>Ma de\u2019 Paperoni \u00e8 l\u2019imprenditore indomito che sappiamo, e avvia una contromossa: accelera la produzione, per tornare a superare Rockerduck sia sulla stagionalit\u00e0 dei prodotti che (ci immaginiamo) sui prezzi. Rockerduck lo segue subito, ma nella sua serra sottomoarina le condizioni climatico-produttive sono particolarmente rischiose, come nota un suo tecnico. Tuttavia vediamo Rockerduck assumersi in toto il rischio: piuttosto che vedersi superato se ne frega delle conseguenze, e ordina che si acceleri la produzione senza rispettare i tempi naturali di crescita delle piante.<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino6s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-858 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino6s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"638\" \/><\/a><a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino7s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-859 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino7s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"636\" \/><\/a><\/p>\n<p>Inizia cos\u00ec una catastrofe. Cominciano a verificarsi problemi serissimi: frutti e verdure marciscono in un baleno, con inevitabili contestazioni dei consumatori. Idem accade alla Underland P.d.P.. La credibilit\u00e0 delle \u201cmegafattorie\u201d \u00e8 distrutta, e la valutazione di Rockerduck \u00e8 impetosa: inutile rimediare tornando ai metodi precedenti:<\/p>\n<blockquote><p>l\u2019immagine dell\u2019azienda ormai \u00e8 compromessa e, in questi casi, il consumatore non perdona!<\/p><\/blockquote>\n<p>Resta da fare solo una cosa: abbandonare del tutto il business. Si chiude. Ai nipotini il ruolo di esplicitare la morale:<\/p>\n<blockquote><p><em>Che batosta per lo Zio Paperone! Ci ha rimesso una vagonata di dollari! Per non parlare di Rockerduck! La cupola sottomarina sar\u00e0 costata anche di pi\u00f9! [\u2026] Con la natura non si scherza! Maltrattandola, ne ricavi solo guai!<\/em><\/p><\/blockquote>\n<p>Insomma, il racconto sul conflitto tra modelli industriali che ne esce \u00e8 certo molto semplifice, ma non anestetizzato. Lo vediamo quindi messo in scena in tuttte le sue fasi, dall\u2019analisi dello scenario competitivo alle strategie di creazione del valore aggiunto, dalla fase di innovazione fino al (drammatico) run-out-of-business. Una piccola lezione di didattica industriale, compiuta e coerente.<\/p>\n<p>3- Nel post-finale, con il \u201critorno alla normalit\u00e0\u201d, la storia aggiunge un ingrediente ulteriore. La scena di Paperopoli, dopo il tracollo dei due antagonisti, torna ad essere dominata dal \u201cmercato dei contadini\u201d. E proprio l\u00ec si ritrovano Nonna Papera e Paperone, con quest\u2019ultimo ormai in veste di (scornato) cliente. E\u2019 qui che la parabola disneyana trova un compimento non solo didattico, ma propriamente pedagogico. Lo rivela Battista, maggiordomo di Paperone, chiacchierando con Nonna Papera cui svela come sono andate \u2018veramente\u2019 le cose nel momento cruciale della scelta di \u201calzare il rischio\u201d:<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino8s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-860 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino8s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"638\" \/><\/a><a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino9s.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-861\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/topolino9s.jpg\" alt=\"Economia solidale... conosciamola con i fumetti!\" width=\"468\" height=\"653\" \/><\/a><\/p>\n<p>Ebbene la scelta di Paperone a favore di un processo produttivo aggressivo e distruttivo, non era finalizzata al recupero della posizione dominante su Rockerduck. Si trattava di un <strong>fallimento industriale intenzionale<\/strong>, il cui obiettivo era altro: fare marcia indietro rispetto a un modello industriale che stava distruggendo un business \u201csano\u201d come quello della filiera corta, alimentato dai contadini.<\/p>\n<p>Ovviamente una storia Disney come questa, breve e semplice, si apre a diverse letture, tra cui:<\/p>\n<ul>\n<li>lettura economicista: a trionfare \u00e8 il cinismo imprenditoriale di Paperone, che piuttosto di perdere la leadership preferisce sfasciare l\u2019intero mercato (Paperone \u00e8 un capitalista spietato, e cos\u00ec si \u00e8 comportato anche stavolta, al di l\u00e0 della facciata buonista)<\/li>\n<li>lettura sarcastica: queste cose possono accadere solo in storielle immaginarie (Paperone \u00e8 un imprenditore lontano anni luce dalla realt\u00e0 imprenditoriale e dall\u2019economia reale)<\/li>\n<\/ul>\n<p>Tutte legittime. E non c\u2019\u00e8 dubbio che ciascuno sia libero di scegliere la propria. Ma quel che mi pare importante \u00e8 riconoscere anche il peso e il valore di quel che una volta si sarebbe chiamato il \u201cmessaggio\u201d: l\u2019obiettivo esplicito, l\u2019intenzione comunicativa della storia.<\/p>\n<p>Ed \u00e8 in questo senso che mi sembra utile sottolineare come <em>Zio Paperone e la campagna in citt\u00e0<\/em>, grazie alla sequenza nel post-finale, non sia solo una storiella su un sano principio (\u2018rispetta la natura\u2019) condita dalla descrizione (compiuta) delle sue implicazioni economico-industriali. Pi\u00f9 ampiamente, \u00e8 una storia su un modo di guardare al business: non solo didattica industriale, ma <strong>pedagogia economica<\/strong>. Dietro alle scelte di business, anche le pi\u00f9 paradossali e impossibili come un *maxifallimento intenzionale*, c\u2019\u00e8 una visione del contesto sociale in cui vanno a radicarsi. Un contesto in cui non tutto \u00e8 utile, non tutto \u00e8 opportuno, non tutto \u00e8 sviluppo.<\/p>\n<p>E per quanto assurdo, illusorio, buonista, credibile-solo-nei-fumetti possa sembrare il messaggio di un Paperon de\u2019 Paperoni, in fondo \u00e8 proprio di questa pedagogia che sembriamo avere pi\u00f9 bisogno oggi, per lo sviluppo della nostra acciaccata societ\u00e0 moderna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noi, del blog di romanews.it, ci teniamo \u00a0a scrivere contenuti originali e assolutamente NON copiati ma, proponendo una sezione WIKI dedicata all&#8217;economia solidale ed ai GAS (gruppi di acquisto solidale),\u00a0siamo rimasti conquistati dalla descrizione in chiave &#8220;cartoons&#8221; fatta da Topolino nel 2011 magistralmente descritta dal blog https:\/\/fumettologicamente.wordpress.com\/tag\/topolino\/page\/3\/ Vi proponiamo quindi, in modalit\u00e0\u00a0&#8220;RASSEGNA STAMPA&#8221;, l&#8217;articolo pubblicato [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[],"class_list":["post-100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-solidale"],"_links":{"self":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/comments?post=100"}],"version-history":[{"count":2,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/100\/revisions"}],"predecessor-version":[{"id":382,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/100\/revisions\/382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media\/101"}],"wp:attachment":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media?parent=100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/categories?post=100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/tags?post=100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}