{"id":122,"date":"2015-11-12T00:00:00","date_gmt":"2015-11-11T23:00:00","guid":{"rendered":"https:\/\/www.romanews.it\/blog\/index.php\/2015\/11\/12\/economia-solidale-tornare-alla-filiera-corta-2\/"},"modified":"2017-10-09T04:08:28","modified_gmt":"2017-10-09T02:08:28","slug":"economia-solidale-tornare-alla-filiera-corta-2","status":"publish","type":"post","link":"https:\/\/www.romanews.it\/blog\/economia-solidale-tornare-alla-filiera-corta-2\/","title":{"rendered":"Economia solidale &#8211; Tornare alla filiera corta"},"content":{"rendered":"<p>[corner-ad id=1]<strong><em>La modernizzazione dell\u2019agricoltura e l\u2019origine della \u201cfiliera\u00a0<\/em><\/strong><strong><em>lunga\u201d<\/em><\/strong><\/p>\n<p>Fino al XX secolo, per gli abitanti dei centri urbani i beni pi\u00f9 facilmente reperibili\u00a0erano quelli prodotti localmente (Schonhart, 2008) da <strong>artigiani e agricoltori, che di solito\u00a0operavano in attivit\u00e0 a carattere familiare<\/strong>. Erano quindi <strong>i contadini a raggiungere le citt\u00e0\u00a0per offrire le proprie merci<\/strong> in un mondo dove il <strong>rapporto tra consumatore e produttore<\/strong> era\u00a0alla base di qualsiasi tipo di commercio.<br \/>\nMa tra l\u2019Ottocento e il \u2018Novecento l\u2019intero assetto sociale, economico e culturale ha\u00a0subito radicali trasformazioni&#8230;<\/p>\n<p><a href=\"https:\/\/www.romanews.it\/blog\/wiki\/la-modernizzazione-dellagricoltura-e-lorigine-della-filiera-lunga\/\" target=\"_blank\" rel=\"noopener\">Clicca qu\u00ec per visualizzare l&#8217;articolo completo nella sezione WIKI del blog<\/a><\/p>\n<p>L&#8217;elenco aggiornato di tutti gli articoli pubblicati su Economia solidale e Gruppi di Acquisto solidale (GAS)\u00a0sono nell&#8217;articolo di Introduzione alla sezione wiki che potete leggere cliccando nel link che segue:<\/p>\n<h1>Filiera corta, prezzo giusto e sviluppo sostenibile: il caso dei Gruppi di Acquisto Solidale a Roma<\/h1>\n<p><a href=\"https:\/\/www.romanews.it\/blog\/wiki\/filiera-corta-prezzo-giusto-e-sviluppo-sostenibile-il-caso-dei-gruppi-di-acquisto-solidale-a-roma\/\">https:\/\/www.romanews.it\/blog\/wiki\/economia-solidale<\/a><\/p>\n<p>Gli articoli sono tratti dalla tesi di laurea del Dr. Giacomo Crisci con il medesimo titolo di cui vedete\u00a0qu\u00ec la copertina.<\/p>\n<p style=\"text-align: left;\">Universit\u00e0 ROMA TRE &#8211; Facolt\u00e0 di Economia &#8220;Federico Caff\u00e8&#8221; &#8211; Anno accademico 2012\/2013<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/Cover-Tesi_Giacomo_Crisci.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-841 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/10\/Cover-Tesi_Giacomo_Crisci.jpg\" alt=\"Economia solidale - Tornare alla filiera corta\" width=\"373\" height=\"555\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[corner-ad id=1]La modernizzazione dell\u2019agricoltura e l\u2019origine della \u201cfiliera\u00a0lunga\u201d Fino al XX secolo, per gli abitanti dei centri urbani i beni pi\u00f9 facilmente reperibili\u00a0erano quelli prodotti localmente (Schonhart, 2008) da artigiani e agricoltori, che di solito\u00a0operavano in attivit\u00e0 a carattere familiare. Erano quindi i contadini a raggiungere le citt\u00e0\u00a0per offrire le proprie merci in un mondo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90,96],"tags":[97,98],"class_list":["post-122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-solidale","category-economia-solidale-gas-a-roma","tag-economia-solidale","tag-filiera-corta"],"_links":{"self":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":2,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/122\/revisions"}],"predecessor-version":[{"id":379,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/122\/revisions\/379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media\/123"}],"wp:attachment":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media?parent=122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/categories?post=122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/tags?post=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}