{"id":136,"date":"2016-01-24T00:00:00","date_gmt":"2016-01-23T23:00:00","guid":{"rendered":"https:\/\/www.romanews.it\/blog\/index.php\/2016\/01\/24\/cosa-sono-le-previsioni-del-tempo-spaziale\/"},"modified":"2017-10-09T02:45:52","modified_gmt":"2017-10-09T00:45:52","slug":"cosa-sono-le-previsioni-del-tempo-spaziale","status":"publish","type":"post","link":"https:\/\/www.romanews.it\/blog\/cosa-sono-le-previsioni-del-tempo-spaziale\/","title":{"rendered":"Cosa sono le previsioni del tempo spaziale"},"content":{"rendered":"<p>Le <strong>previsioni del tempo spaziale<\/strong>\u00a0 ormai da anni \u00a0sono realizzate grazie al <strong>Super DARN<\/strong> &#8211; Super Dual Auroral Radar Network &#8211; che \u00e8 un progetto internazionale per lo studio dello spazio circumterrestre.<br \/>\nL&#8217;Italia ospit\u00f2 a\u00a0Venezia un workshop internazionale, Super DARN, da parte dell\u2019Istituto di Fisica dello Spazio Interplanetario del Consiglio Nazionale delle Ricerche.<br \/>\nLe previsioni del tempo \u201cspaziale\u201d saranno in futuro sempre pi\u00f9 importanti; i fenomeni <strong>magnetosferici<\/strong> e <strong>ionosferici<\/strong>, causati dalle variazioni delle condizioni del <strong>sole<\/strong> e del <strong>vento solare<\/strong>, possono determinare disfunzioni non solo sul funzionamento e l\u2019affidabilit\u00e0 delle istallazioni spaziali, ma anche creare danni sulla terra, ad esempio alle reti di approvvigionamento dell\u2019<strong>energia elettrica<\/strong>, agli oleodotti, alle operazioni di lancio missilistico, ai sistemi spaziali, alle comunicazioni, al clima.<br \/>\nL\u2019Italia partecipa al \u00a0<strong>SuperDARN<\/strong>\u00a0 avendo partecipato\u00a0all&#8217;istallazione\u00a0di uno dei radar \u00a0nell\u2019isola Kerguelen, in\u00a0oceano indiano, insieme\u00a0con l\u2019LPCE (Laboratoire de Physique et Che mie de l\u2019Environment, di Orleans, Francia.<br \/>\nI workshops consentiranno di fare il punto sullo stato dei progressi compiuti nei settori delle operazioni radar, sia a livello <strong>hardware<\/strong>, sia <strong>software<\/strong>, nonch\u00e9 sulla fisica dei plasmi, e su tutti quei fenomeni legati alle relazioni <strong>Sole-Terra.<\/strong><br \/>\nIn realt\u00e0 si tratta di uno dei pi\u00f9 recenti ed avanzati sistemi per lo studio degli effetti del <strong>plasma solare<\/strong> sulla <strong>magnetosfera<\/strong> e <strong>ionosfera<\/strong> terrestre: le <strong>Aurore Polari<\/strong>.<br \/>\nLe aurore sono formazioni luminose di colori e forme variabili, a <strong>latitudini magnetiche<\/strong> tra i 60 e 70 gradi.<br \/>\nSono causate all\u2019emissione di luce seguente all\u2019eccitazione di atomi e molecole ionosferiche una volta \u201curtati\u201d da elettroni e protoni di provenienza solare.<br \/>\nSi osservano ad alte latitudini in quanto queste regioni sono connesse magneticamente con zone dello <strong>spazio circumterrestre<\/strong> da cui i <strong>protoni<\/strong> e, soprattutto, gli <strong>elettroni<\/strong>, possono precipitare molto facilmente, scorrendo lungo le linee di forza del <strong>campo geomagnetico<\/strong>.<br \/>\nLe misure vengono effettuate con una rete di 15 Radar HF (8-20 MHz) posizionati nelle regioni <strong>artiche<\/strong> ed <strong>antartiche<\/strong>, i siti privilegiati per le osservazioni da terra dei fenomeni, che hanno origine dall\u2019interazione fra il <strong>vento solare<\/strong> e la <strong>magnetosfera<\/strong>.<br \/>\nL\u2019incrocio dei dati provenienti dai singoli radar permetter\u00e0 di costruire, istante per istante, la mappa della <strong>circolazione del gas ionizzato<\/strong> della <strong>ionosfera<\/strong> intorno ai <strong>poli magnetici<\/strong>, fra i 100 e 400 km di altezza.<\/p>\n<p>Si \u00e8 parlato di probabili interazioni con il <strong>clima<\/strong>, e di conseguenza sulla <strong>salute umana<\/strong>: fastidiosi disturbi fisici che potrebbero derivare dal <strong>vento spaziale<\/strong>. <strong>Variazione sull\u2019umore<\/strong> e disturbi connessi alla <strong>meteoropatia<\/strong>; di certo si sa che coloro che viaggiano spesso in aereo, a latitudini elevate, possono essere interessati a <strong><em>forti dosi<\/em> <\/strong>di <strong>radiazioni particellare ed elettromagnetica<\/strong>, tali da poter alterare il normale ciclo biologico.<\/p>\n<p>Si \u00e8 finalmente preso atto della possibilit\u00e0 dei danni, causati da <strong>particelle cosmiche<\/strong>, ai <strong>passeggeri di aerei<\/strong>, cosa sempre negata dalle compagnie di tutto il mondo: \u00e8 famosa la frase \u201c<strong>non \u00e8 stato sufficientemente dimostrato da un punto di vista scientifico che\u2026.<\/strong>\u201d; una seconda riflessione \u00e8 notare come molti, quasi tutti, i progetti nazionale ed internazionali abbiano un\u2019appendice di finalit\u00e0 riconducibile alla <strong>salute umana<\/strong> o alla tutela dell\u2019<strong>ambiente<\/strong>, o a tutte e due.<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/01\/sole-radiazioni.jpg\" rel=\"attachment wp-att-1183\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1183 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/01\/sole-radiazioni.jpg\" alt=\"Cosa sono le previsioni del tempo spaziale\" width=\"500\" height=\"410\" \/><\/a>Sarebbe interessante verificare quanta energia verr\u00e0 dedicata alla tutela della salute!<br \/>\nNel caso del <strong>SuperDARN<\/strong>, appena riportato, le risorse economiche sul tavolo sono ingentissime, l\u2019installazione della rete dei quindici <strong>radar HF<\/strong>, la costruzione dei siti, i laboratori ed il resto dell\u2019indotto consentir\u00e0 \u201cla costruzione, istante per istante, della mappa della circolazione del gas ionizzato della ionosfera\u2026\u201d.<br \/>\nSi vorrebbe conoscere anche quando verranno portate avanti le ricerche sui \u201c<strong>disturbi fisici<\/strong>\u201d subiti dall\u2019uomo, citati dal progetto, si vorrebbe sapere in quale sottoprogetto verranno trattati, a livello scientifico, le interazioni con il clima, ed in quale laboratorio verranno sperimentati materiali a tutela dei passeggeri utenti di aerei.<br \/>\nE\u2019 compito primario della societ\u00e0 civile proteggere il cittadino utente e consumatore, essere da stimolo alle istituzione, nell\u2019esercizio delle proprie funzioni, di promozione e di controllo.<\/p>\n<p><a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/01\/Tokke_sign8.jpg\" rel=\"attachment wp-att-1202\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1202 alignright\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/01\/Tokke_sign8.jpg\" alt=\"Tokke_sign8\" width=\"250\" height=\"59\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le previsioni del tempo spaziale\u00a0 ormai da anni \u00a0sono realizzate grazie al Super DARN &#8211; Super Dual Auroral Radar Network &#8211; che \u00e8 un progetto internazionale per lo studio dello spazio circumterrestre. L&#8217;Italia ospit\u00f2 a\u00a0Venezia un workshop internazionale, Super DARN, da parte dell\u2019Istituto di Fisica dello Spazio Interplanetario del Consiglio Nazionale delle Ricerche. Le previsioni [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,13],"tags":[109,110],"class_list":["post-136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-e-spettacolo","category-scienza-e-conoscenza","tag-previsione-del-tempo-spaziale","tag-previsioni-del-tempo"],"_links":{"self":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":1,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/136\/revisions"}],"predecessor-version":[{"id":339,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/136\/revisions\/339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media\/137"}],"wp:attachment":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media?parent=136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/categories?post=136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/tags?post=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}