{"id":211,"date":"2017-08-19T00:00:00","date_gmt":"2017-08-18T22:00:00","guid":{"rendered":"https:\/\/www.romanews.it\/blog\/index.php\/2017\/08\/19\/helpinthecity-org-trovare-volontariato\/"},"modified":"2019-05-05T18:15:38","modified_gmt":"2019-05-05T16:15:38","slug":"helpinthecity-org-trovare-volontariato","status":"publish","type":"post","link":"https:\/\/www.romanews.it\/blog\/helpinthecity-org-trovare-volontariato\/","title":{"rendered":"helpinthecity.org per trovare dove fare volontariato"},"content":{"rendered":"<p>Se vuoi fare <strong>volontariato<\/strong>\u00a0spesso il problema \u00e8 scoprire dove poterlo fare e soprattutto avere informazioni sul tipo di attivit\u00e0 che andrai ad eseguire al fine di fare qualcosa che puoi concretamente effettuare in modo efficace perch\u00e9 adatta alle tue competenze e attitudini.\u00a0 Nonostante <strong>aiutare il prossimo<\/strong> sia comunque un gesto importante, \u00e8 anche importante fare qualcosa che sentiamo in modo pi\u00f9 forte e chiaro in conseguenza di un vissuto personale, una sensibilizzazione, una conoscenza anche casuale che ci ha portato a percepire un <strong>problema sociale<\/strong> che altrimenti si sarebbe confuso nella moltitudine dei disagi del mondo attuale.<br \/>\nSpesso c&#8217;\u00e8 una categoria di <strong>persone disabili<\/strong> o comunque che hanno dei problemi che attira di pi\u00f9 la nostra attenzione perch\u00e9 abbiamo vissuto un&#8217;esperienza individuale oppure semplicemente riteniamo che \u00e8 pi\u00f9 importante <strong>aiutare<\/strong> determinate categorie.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4855 size-full\" title=\"fare volontariato\" src=\"http:\/\/www.helpinthecity.org\/librisolidali\/wp-content\/uploads\/2017\/08\/helpinthecity-org-pr.jpg\" alt=\"helpinthecity.org - cerca dove fare volontariato\" width=\"700\" height=\"504\" \/><\/p>\n<p>E poi, ultimo ma non meno importante, l\u2019<strong>attivit\u00e0 solidale<\/strong> di <strong>volontariato<\/strong> dovrebbe essere vicina a dove abitiamo o lavoriamo al fine di meglio collaborare.<br \/>\nEsistono mille altre sfumature di queste situazioni compresa la possibilit\u00e0 anche di <strong>fare volontariato<\/strong> e imparare a fare un lavoro e magari trovarlo.<br \/>\nIn tutto questa importanti dinamiche di vita vissuta, nonostante internet con Google, YouTube, Facebook e tutti gli altri social che collegano oltre due miliardi di persone, la ricerca dell&#8217;Associazione pi\u00f9 vicina al nostro quartiere \u00e8 molto difficile e alla portata solo di specialisti web e resta \u00a0praticamente impossibile per la maggior parte delle persone.<br \/>\nInfatti non esiste su web un sistema che ci permetta di avvicinarci a questo mondo e di renderci conto di dove soprattutto possiamo anche essere pi\u00f9 utili.<br \/>\nAlcune importanti <strong>associazioni<\/strong> che rappresentano il mondo del volontariato italiano hanno ammesso questa carenza a livello web di strumenti di informazione sia per chi vuole fare volontariato sia per le <strong>associazioni<\/strong> che ricercano <strong>volontari<\/strong>.<br \/>\nEsistono ovviamente migliaia di siti che pubblicano informazioni sulle singole <strong>associazioni<\/strong> ma la realt\u00e0 globale delle associazioni distribuite sul territorio sfugge a questa offerta informativa e la maggior parte delle <strong>associazioni<\/strong> che si propone su web ha vantaggi minimi o nulli.<br \/>\nPurtroppo pubblicare semplicemente una lista delle decine di migliaia di <strong>associazioni<\/strong> distribuite sul territorio italiano non sarebbe concretamente utile.<\/p>\n<p>Chi ha una pur minima esperienza di <strong>SEO<\/strong> (search engine optimization) sapr\u00e0 che occorre molto impegno e competenza perch\u00e9 un sito possa essere concretamente visibile e ritrovabile sui motori di ricerca e soprattutto su Google, il \u201cprincipe\u201d dei motori di ricerca.<\/p>\n<p>La associazione <strong>link UP Europe!<\/strong> dopo un esperienza nel settore durata due decenni, applicata soprattutto nelle questioni etiche riguardo la comunicazione su web, ha sviluppato una piattaforma informatica molto semplice graficamente accattivante dove trovare le associazioni presenti sul territorio. Un&#8217;idea semplice ma che finora nessuno aveva realizzato.<\/p>\n<p>Purtroppo il progetto, gi\u00e0 ben ideato nei dettagli, necessita ancora di molto lavoro per essere realizzato.<br \/>\nChi vuole saperne di pi\u00f9 pu\u00f2 iscriversi alla newsletter collegandosi al portale<br \/>\n<a href=\"http:\/\/www.helpinthecity.org\/home\">http:\/\/www.helpinthecity.org\/home<\/a><br \/>\nPer sostenere il progetto \u00e8 anche attiva una sezione ecommerce per l\u2019acquisto di libri<br \/>\n<a href=\"http:\/\/www.helpinthecity.org\/librisolidali\">http:\/\/www.helpinthecity.org\/librisolidali<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se vuoi fare volontariato\u00a0spesso il problema \u00e8 scoprire dove poterlo fare e soprattutto avere informazioni sul tipo di attivit\u00e0 che andrai ad eseguire al fine di fare qualcosa che puoi concretamente effettuare in modo efficace perch\u00e9 adatta alle tue competenze e attitudini.\u00a0 Nonostante aiutare il prossimo sia comunque un gesto importante, \u00e8 anche importante fare [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[69,165],"tags":[166,167,168,169],"class_list":["post-211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etica-e-societa","category-non-profit-volontariato","tag-associazioni","tag-fare-volontariato","tag-helpinthecity-org","tag-volontariato"],"_links":{"self":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/comments?post=211"}],"version-history":[{"count":1,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/211\/revisions"}],"predecessor-version":[{"id":275,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/211\/revisions\/275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media\/274"}],"wp:attachment":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media?parent=211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/categories?post=211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/tags?post=211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}