{"id":234,"date":"2015-12-10T00:00:00","date_gmt":"2015-12-09T23:00:00","guid":{"rendered":"https:\/\/www.romanews.it\/blog\/index.php\/i-farmers-market-mercati-dei-contadini\/"},"modified":"2017-10-09T02:48:13","modified_gmt":"2017-10-09T00:48:13","slug":"i-farmers-market-mercati-dei-contadini","status":"publish","type":"post","link":"https:\/\/www.romanews.it\/blog\/i-farmers-market-mercati-dei-contadini\/","title":{"rendered":"I Mercati dei contadini  &#8211; (Farmers\u2019 Market)"},"content":{"rendered":"<p>[corner-ad id=1]<\/p>\n<p style=\"text-align: center;\">[wp_bannerize group=&#8221;AdSense_Adattibile&#8221;]<\/p>\n<h1>I mercati dei contadini<\/h1>\n<p><strong>Farmers\u2019 Market<\/strong> (FM) significa letteralmente \u201c<em>mercati dei contadini<\/em>\u201d o \u201c<em>mercati\u00a0contadini<\/em>\u201d e si tratta di una delle forme di <strong>filiera corta<\/strong> promosse soprattutto da associazioni\u00a0di agricoltori. I <strong>Farmers\u2019 Market<\/strong> si svolgono spesso in aree riqualificate delle citt\u00e0, in cui\u00a0gli agricoltori stessi si recano, generalmente una o due volte a settimana, per montare i\u00a0propri banchi e vendere i prodotti disponibili a seconda della stagione (Marino &#038;\u00a0Cicatiello, 2012). <a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/12\/mercati-contadini_J.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1075 size-full aligncenter\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/12\/mercati-contadini_J.jpg\" alt=\"I Mercati dei contadini - (Farmers\u2019 Market)\" width=\"650\" height=\"498\" \/><\/a><br \/>\nLo sviluppo di questi mercati in <strong>Europa<\/strong> si deve soprattutto alla presenza\u00a0di attivit\u00e0 tradizionali locali che rivendicano un concetto di qualit\u00e0 basato sulla\u00a0<strong>sostenibilit\u00e0<\/strong> e sul benessere animale (Sonnino &#038; Marsden, 2006; Ilbery &#038; Maye, 2005).\u00a0Questi mercati sono frequentati abitualmente da consumatori residenti nelle aree limitrofe\u00a0al mercato. I <strong>Farmers\u2019 Market<\/strong> non comprendono solo agricoltori, ma anche piccole\u00a0aziende di artigianato o di abbigliamento, che utilizzano tecniche rispettose dell\u2019ambiente\u00a0e materiali <strong>naturali<\/strong>, <strong>riciclabili<\/strong> o <strong>riciclati<\/strong>.\u00a0Il primo mercato contadino \u00e8 stato organizzato in Canada nel 1780. In seguito, nel\u00a01973 \u00e8 stato fondato l\u2019<strong>Ontario Farm Fresh Marketing Association<\/strong> (<strong>OFFMA<\/strong>),\u00a0un\u2019associazione proprio con lo scopo di coordinare le varie esperienze di mercati degli\u00a0agricoltori. Questi ultimi si sono sviluppati a partire dagli anni Novanta negli Stati Uniti,\u00a0dove la <strong>biologicit\u00e0<\/strong> e la <strong>localit\u00e0<\/strong> dei prodotti erano considerati una filosofia di vita gi\u00e0 da\u00a0diversi anni. Il fenomeno ha guadagnato popolarit\u00e0 dopo l\u2019attenzione dei consumatori\u00a0verso la qualit\u00e0 (Vecchio, 2009) e costituisce, oggi, una realt\u00e0 consolidata negli Stati Uniti.\u00a0I dati dell\u2019United States Department of Agriculture24 (USDA \u00a0<a href=\"http:\/\/www.usda.gov\" rel=\"nofollow\">http:\/\/www.usda.gov<\/a>) contano 4.385 mercati attivi\u00a0sul territorio nazionale nel 2006, con una crescita quasi del 150% dalle 1.755 unit\u00e0 nel\u00a01994 (anno del primo censimento).<br \/>\nDal 2000 i <strong>mercati contadini<\/strong> rappresentano una\u00a0forma diffusa che coinvolge oltre 2.760.000 consumatori ogni settimana. In <strong>Europa<\/strong> il\u00a0fenomeno \u00e8 pi\u00f9 recente: in Gran Bretagna i primi mercati furono inaugurati negli anni\u00a0Novanta e oggi, secondo i dati della <strong>National Farmers&#8217; Retail &#038; Markets association<\/strong>\u00a0(<strong>FARMA<\/strong>) , se ne contano oltre 550 per un giro d\u2019affari di oltre 300 milioni di euro.<br \/>\nL\u2019Italia \u00e8 probabilmente il paese europeo pi\u00f9 ricco di queste iniziative. I mercati dei\u00a0contadini sono organizzati prevalentemente da associazioni quali \u00a0<strong>Coldiretti<\/strong>, <strong>Slow Food<\/strong>,\u00a0<strong>AIAB<\/strong> e associazioni libere di produttori. L\u2019esperienza pi\u00f9 diffusa \u00e8 quella rappresentata\u00a0dai mercati della <strong>Fondazione Campagna Amica di Coldiretti<\/strong> con oltre mille iniziative\u00a0sparse su tutto il territorio.<\/p>\n<p style=\"text-align: center;\">[wp_bannerize group=&#8221;romanews.ir_336x280&#8243;]<\/p>\n<p>La Fondazione organizza i mercati (\u201c<strong>Mercati di Campagna\u00a0Amica<\/strong>\u201d, MCA) al fine di \u201cpromuovere l\u2019estensione capillare dei mercati degli agricoltori e\u00a0di ogni formula di vendita diretta\u201d per valorizzare le produzioni locali e rispondere alla\u00a0crescente domanda di cibo genuino.\u00a0Ai MCA partecipano agricoltori associati, di solito operanti nella stessa regione in\u00a0cui \u00e8 ospitato il mercato, che vendono direttamente le proprie produzioni.<br \/>\nI produttori sono\u00a0tenuti al rispetto di un regolamento disciplinare che prevede, tra l&#8217;altro, il controllo dei\u00a0prezzi massimi praticati, secondo quanto stabilito da un accordo quadro con le principali\u00a0Associazioni di Consumatori italiane.<\/p>\n<blockquote><p>Siti web di riferimento:<br \/>\n<a href=\"http:\/\/www.farmersmarkets.net\" target=\"_blank\" rel=\"nofollow\">www.farmersmarkets.net<\/a><br \/>\nLa Confederazione Nazionale Coltivatori Diretti (Coldiretti) \u00e8 la maggiore associazione di rappresentanza e\u00a0assistenza dell&#8217;agricoltura italiana. <a href=\"http:\/\/www.coldiretti.it\" target=\"_blank\">http:\/\/www.coldiretti.it<\/a><br \/>\nL\u2019Associazione Italiana per l\u2019Agricoltura Biologica (AIAB) \u00e8 una associazione di produttori, tecnici e cittadini consumatori. <a href=\"http:\/\/www.farmersmarkets.net\" target=\"_blank\">www.aiab.it<br \/>\n<\/a><a href=\"http:\/\/www.campagnamica.it\" target=\"_blank\" rel=\"nofollow\">www.campagnamica.it<\/a><\/p><\/blockquote>\n<p>Nei MCA i produttori accreditati, secondo le regole\u00a0stabilite dal regolamento disciplinare, si impegnano a garantire in modo trasparente un\u00a0risparmio di almeno il 30% rispetto ai prezzi dei prodotti confrontabili comunicati tramite &#8220;<strong>SMS consumatori<\/strong>&#8220;. I produttori si impegnano altres\u00ec a garantire la provenienza, la\u00a0tracciabilit\u00e0, la qualit\u00e0 e la salubrit\u00e0 dei prodotti in vendita.\u00a0Aderendo al progetto gli agricoltori hanno la \u00a0possibilit\u00e0 di apporre il marchio di\u00a0riconoscimento \u201c<strong>Campagna Amica<\/strong>\u201d, che contraddistingue il prodotto agricolo \u201ccento per\u00a0cento italiano firmato dagli agricoltori\u201d. I prodotti cos\u00ec tutelati sono offerti attraverso\u00a0un\u2019estesa rete commerciale nazionale sotto diverse forme.<br \/>\nLa Fondazione, infatti, non si\u00a0limita all\u2019organizzazione dei mercati, ma affianca a questi anche punti vendita in citt\u00e0,\u00a0(chiamati \u201c<strong>Botteghe di Campagna Amica<\/strong>\u201d o \u201c<strong>Botteghe italiane<\/strong>\u201d), presso cooperative,\u00a0consorzi agrari, agriturismi, aziende agricole, coinvolgendo inoltre la rete della\u00a0ristorazione a chilometri zero e dei Gruppi di Acquisto Solidali.<\/p>\n<h1><em>I Box Schemes<br \/>\n<\/em><\/h1>\n<p>Il <strong>Box Schemes<\/strong> \u00e8 una forma distributiva organizzata dall\u2019<strong>agricoltore<\/strong> che si occupa\u00a0del rifornimento di prodotti \u00a0<strong>agricoli stagionali<\/strong> (<strong>solitamente biologici<\/strong>) per un gruppo di\u00a0consumatori convenzionati, i quali accolgono la merce direttamente in casa o al lavoro.<br \/>\nQuesto servizio viene proposto spesso sotto forma di abbonamento settimanale,\u00a0quindicinale o a richiesta. Ci\u00f2 che viene recapitato a casa dell\u2019acquirente \u00e8 il cosiddetto\u00a0\u201c<strong>cassettone<\/strong>\u201d (o box), la cui composizione \u00e8 definita in base alla disponibilit\u00e0. Per offrire\u00a0una combinazione di prodotti pi\u00f9 appetibile, le aziende agricole sono spinte a cooperare in\u00a0forma associata o fondando <strong>cooperative<\/strong> vere e proprie.<br \/>\nTalvolta la produzione aziendale, o\u00a0di cooperativa, pu\u00f2 essere integrata con prodotti importati che rispettino determinate\u00a0caratteristiche. Solitamente quando vi \u00e8 un\u2019ampia disponibilit\u00e0 di scelta, i consumatori\u00a0possono scegliere le quantit\u00e0 e la composizione del loro \u201c<strong>cassettone<\/strong>\u201d. I vantaggi maggiori\u00a0per il consumatore sono legati alla <strong>freschezza<\/strong>, alla <strong>qualit\u00e0<\/strong>, alla <strong>variet\u00e0<\/strong> e alla <strong>consegna a\u00a0domicilio<\/strong>, oltre a un ritrovato <strong>contatto diretto<\/strong> col produttore.<br \/>\nGli svantaggi sono collegati\u00a0al costo che pu\u00f2 essere alto per via della <strong>consegna a domicilio<\/strong>. Questa forma di\u00a0distribuzione \u00e8 molto popolare negli USA, in Canada e nel Nord Europa. In Gran Bretagna\u00a0la Soil Association ha indicato che il fatturato delle iniziative di <strong>box schemes<\/strong>\u00a0corrispondeva a oltre 174 milioni di sterline nel 2012, con un aumento del 4,4% rispetto\u00a0all\u2019anno precedente.<br \/>\n<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/12\/IoChiamoBio_J.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1077 size-full aligncenter\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2015\/12\/IoChiamoBio_J.jpg\" alt=\"I Mercati dei contadini - (Farmers\u2019 Market)\" width=\"650\" height=\"307\" \/><\/a><br \/>\nIn Italia, <strong>Bio bank<\/strong> (2013) ha censito 130 aziende che praticano\u00a0vendita online di prodotti aziendali con un incremento del 20%.<br \/>\nUna crescita che si\u00a0inserisce a pieno titolo in quella pi\u00f9 generale della vendita diretta che nel 2012 \u00e8\u00a0\u00a0aumentata del 4,9%. La maggior parte delle aziende propone esclusivamente la vendita di\u00a0<strong>prodotti biologici<\/strong>.<\/p>\n<p style=\"text-align: center;\">[wp_bannerize group=&#8221;link_adattabile&#8221;]<\/p>\n<p>Al primo posto in assoluto \u00e8 la <strong>Toscana<\/strong>, con 18 siti (13,8%), seguita\u00a0dalla <strong>Puglia<\/strong>, con 16 (12,3%) e dalle regioni <strong>Emilia-Romagna<\/strong> e \u00a0<strong>Sicilia<\/strong>, allineate su 15 ecommerce\u00a0(11,5%). Dal 2004 opera su Roma &#8220;<strong>Officinae Bio<\/strong>&#8220;, una Cooperativa di 12\u00a0aziende agricole biologiche certificate. L\u2019offerta consiste in un &#8220;Cassettone Bio&#8221; da 4,5 o 9\u00a0kg di frutta e verdura di stagione venduta a prezzo fisso.<br \/>\nLa maggior parte sono aziende\u00a0del territorio laziale, ma i prodotti come agrumi o mele provengono da soci di regioni pi\u00f9\u00a0vocate (Toscana e Calabria).<\/p>\n<p>Articolo tratto dalla tesi di laurea del Dr. Giacomo Crisci:<br \/>\n&#8220;Filiera corta, prezzo giusto e sviluppo sostenibile: il caso<br \/>\ndei Gruppi di Acquisto Solidale a Roma&#8221;<\/p>\n<p style=\"text-align: left;\">Universit\u00e0 ROMA TRE &#8211; Facolt\u00e0 di Economia &#8220;Federico Caff\u00e8&#8221; &#8211; Anno accademico 2012\/2013<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[corner-ad id=1] [wp_bannerize group=&#8221;AdSense_Adattibile&#8221;] I mercati dei contadini Farmers\u2019 Market (FM) significa letteralmente \u201cmercati dei contadini\u201d o \u201cmercati\u00a0contadini\u201d e si tratta di una delle forme di filiera corta promosse soprattutto da associazioni\u00a0di agricoltori. I Farmers\u2019 Market si svolgono spesso in aree riqualificate delle citt\u00e0, in cui\u00a0gli agricoltori stessi si recano, generalmente una o due volte [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[],"class_list":["post-234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-solidale"],"_links":{"self":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/comments?post=234"}],"version-history":[{"count":1,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/234\/revisions"}],"predecessor-version":[{"id":313,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/234\/revisions\/313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media\/235"}],"wp:attachment":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media?parent=234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/categories?post=234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/tags?post=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}