{"id":250,"date":"2016-04-02T00:00:00","date_gmt":"2016-04-01T22:00:00","guid":{"rendered":"https:\/\/www.romanews.it\/blog\/index.php\/i-criteri-del-consumo-critico\/"},"modified":"2017-10-09T02:44:19","modified_gmt":"2017-10-09T00:44:19","slug":"i-criteri-del-consumo-critico","status":"publish","type":"post","link":"https:\/\/www.romanews.it\/blog\/i-criteri-del-consumo-critico\/","title":{"rendered":"I criteri del consumo critico"},"content":{"rendered":"<p>[corner-ad id=1]<\/p>\n<p style=\"text-align: center;\">[wp_bannerize group=&#8221;AdSense_Adattibile&#8221;]<\/p>\n<h1>I criteri<\/h1>\n<p>In <em>&#8220;Guida al consumo critico&#8221;<\/em>\u00a0sono state elencate sei pratiche su cui basare la spesa responsabile: sobriet\u00e0, lotta ai rifiuti, consumo locale e naturale, commercio equo, attenzione al comportamento della imprese, consumo senza crudelt\u00e0. Queste sono pi\u00f9 che altro delle indicazioni che invitano a porsi delle domande nell&#8217;ambito dell&#8217;acquisto di un prodotto. I principi etici<sup>\u00a0<\/sup>si riferiscono sia all&#8217;attenzione verso le pratiche messe in atto dalle aziende, sia alle caratteristiche dei prodotti.\u00a0<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/04\/carciofi.jpg\" rel=\"attachment wp-att-1351\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1351 size-full\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/04\/carciofi.jpg\" alt=\"I criteri del consumo critico\" width=\"650\" height=\"459\" \/><\/a><br \/>\nNei confronti delle aziende questi principi sono rivolti a:<\/p>\n<ul>\n<li><strong>Rispetto dei diritti dei lavoratori<\/strong>: sono evitate le aziende in cui non sono garantiti i diritti dei lavoratori e che delocalizzano la produzione. L&#8217;attenzione a massima per i produttori dei paesi a Sud del mondo per i quali e preferito l&#8217;acquisto dei prodotti equo-solidali che assicurano loro un compenso equo.<\/li>\n<li><strong>Rispetto dell&#8217;ambiente<\/strong>: le aziende che attuano pratiche dannose per l&#8217;ambiente sono escluse in favore di quelle che applicano criteri e certificazioni che garantiscono it rispetto dell&#8217; ambiente.<\/li>\n<li><strong>Aspetti finanziari<\/strong>: sono evitate le aziende che investono in settori speculativi o che comunque non sono eticamente accettabili.<\/li>\n<li><strong>Dimensioni delle imprese<\/strong>: vengono preferite le aziende di piccole dimensioni, che hanno poco potere di mercato e che hanno un legame pi\u00f9 stretto con le tradizioni e le usanze locali. Le imprese multinazionali sono invece evitate.<\/li>\n<li><strong>Boicottaggio<\/strong>: viene messo in pratica nei confronti di quelle aziende, soprattutto quelle internazionali, che adottano pratiche scorrette nei confronti dei lavoratori, dei consumatori o dannose nei confronti dell&#8217;ambiente.<a href=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/04\/trebbiatrice.jpg\" rel=\"attachment wp-att-1352\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1352\" src=\"https:\/\/www.romanews.it\/blog\/wp-content\/uploads\/2016\/04\/trebbiatrice.jpg\" alt=\"I criteri del consumo critico\" width=\"650\" height=\"366\" \/><\/a><\/li>\n<\/ul>\n<p>Per quanto riguarda i prodotti in se si tengono in considerazione diversi aspetti:<\/p>\n<ul>\n<li><strong>Imballaggi minimi<\/strong>: le consegne sono gestite per contemplare it minor numero di imballaggi. Al massimo questi devono essere riciclabili, riciclati, biodegradabili o compostabili. Spesso viene promosso it riciclo dei barattoli e di altri contenitori.<\/li>\n<li><strong>Ciclo produttivo<\/strong>: sono da preferire le materie prodotte con un basso impatto ambientale o provenienti dal riciclo. Sono preferite le produzioni da energie rinnovabili e poco inquinanti.<\/li>\n<li><strong>Durabilit\u00e0<\/strong>: sono preferiti i prodotti che durano nel tempo a quelli usa e getta.<\/li>\n<li><strong>Provenienza<\/strong>: la provenienza del prodotto deve essere certa, tracciabile e locale, o comunque pi\u00f9 vicino possibile, al fine di contenere le <em>foodmiles, <\/em>di tutelare la freschezza e di instaurare rapporti di vicinanza con i produttori (vedi gite o aiuto nella raccolta dei prodotti).<\/li>\n<li><strong>Freschezza e la stagionalit\u00e0<\/strong>: sono da preferire i prodotti freschi e di stagione per contenere l&#8217;energia necessaria alla produzione in serra o al congelamento.<\/li>\n<\/ul>\n<blockquote><p>\u00a0Centro Nuovo Modello di Sviluppo (2011), <em>&#8220;Guida al <\/em><em>Consamo Critico&#8221; <\/em>Ponte alle Grazie,<\/p>\n<p>Movimento Gocce di Giustizia,\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <em>Guida al consumo critico e al boicottaggio&#8221;, <\/em>La Tortuga<\/p>\n<p><a href=\"http:\/\/www.unimondo.org\/Guide\/Economia\/Consumo-critico\" target=\"_blank\">www.unimondo.org<u>\/Cons<\/u><u>umo-<\/u><u>c<\/u><u>ri<\/u><u>tico<\/u><\/a><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">[wp_bannerize group=&#8221;romanews.ir_336x280&#8243;]<\/p>\n<p>Inoltre sono preferiti prodotti\u00a0poco trasformati anche per promuovere la socialit\u00e0 e il recupero del piacere nel cucinare e condividere.\u00a0Metodi di coltivazione naturali: i metodi biologici, biodinamici o naturali sono da preferire per il fatto di essere maggiormente rispettosi dell&#8217;ambiente e delle condizioni di lavoro.<br \/>\nQuello del consumo critico \u00e8\u00a0un pensiero che pu\u00f2 essere portato avanti sia a livello singolo che collettivo. A riguardo i Gruppi di Acquisto Solidali rappresentano una realt\u00e0 molto complessa dei fenomeni che costituiscono il consumo critico, apprezzabile soprattutto se osservata da vicino. Con queste pratiche i consumatori dimostrano che possibile conciliare il proprio benessere con l&#8217;acquisto di prodotti etici ed ecologici, rispettosi della societ\u00e0.<br \/>\nIl fenomeno dei GAS appare un mondo molto compatto anche se presenta molte ambivalenze e contraddizioni: le sfide che si pongono sono soprattutto quelle di costruire un sistema alternativo di approvvigionamento alimentare che prenda in considerazione il cambiamento delle abitudini e il perseguimento del risparmio (Williams e Paddock, 2003).<\/p>\n<p>Articolo tratto dalla tesi di laurea del Dr. Giacomo Crisci:<br \/>\n&#8220;Filiera corta, prezzo giusto e sviluppo sostenibile: il caso<br \/>\ndei Gruppi di Acquisto Solidale a Roma&#8221;<\/p>\n<p style=\"text-align: left;\">Universit\u00e0 ROMA TRE &#8211; Facolt\u00e0 di Economia &#8220;Federico Caff\u00e8&#8221; &#8211; Anno accademico 2012\/2013<\/p>\n<p><strong><em>Continuate a leggere gli altri articoli WIKI su &#8220;Economia solidale&#8221; cliccando nell&#8217;indice contenuto nel widget a destra<\/em><\/strong><\/p>\n<p style=\"text-align: center;\">[wp_bannerize group=&#8221;link_adattabile&#8221;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[corner-ad id=1] [wp_bannerize group=&#8221;AdSense_Adattibile&#8221;] I criteri In &#8220;Guida al consumo critico&#8221;\u00a0sono state elencate sei pratiche su cui basare la spesa responsabile: sobriet\u00e0, lotta ai rifiuti, consumo locale e naturale, commercio equo, attenzione al comportamento della imprese, consumo senza crudelt\u00e0. Queste sono pi\u00f9 che altro delle indicazioni che invitano a porsi delle domande nell&#8217;ambito dell&#8217;acquisto di [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90],"tags":[],"class_list":["post-250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-solidale"],"_links":{"self":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/comments?post=250"}],"version-history":[{"count":1,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/250\/revisions"}],"predecessor-version":[{"id":309,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/250\/revisions\/309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media\/251"}],"wp:attachment":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media?parent=250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/categories?post=250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/tags?post=250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}