{"id":455,"date":"2023-01-11T11:28:04","date_gmt":"2023-01-11T10:28:04","guid":{"rendered":"https:\/\/www.romanews.it\/blog\/?p=455"},"modified":"2020-01-11T11:55:14","modified_gmt":"2020-01-11T10:55:14","slug":"roma-tutti-i-divieti-visti-dagli-stranieri","status":"publish","type":"post","link":"https:\/\/www.romanews.it\/blog\/roma-tutti-i-divieti-visti-dagli-stranieri\/","title":{"rendered":"Roma &#8211; tutti i divieti visti dagli stranieri"},"content":{"rendered":"<header class=\"clearfix\">\n<h1>Vacanze in Italia: Roma vieta questo nelle famose attrazioni turistiche &#8211; sei a favore o contro?<\/h1>\n<h3>ROMA, la capitale d&#8217;Italia, ha preso l&#8217;ennesima misura drastica per contenere l&#8217;eccesso di turismo nelle sue attrazioni pi\u00f9 popolari.\u00a0La citt\u00e0 ha vietato le bancarelle di souvenir nei principali siti turistici tra cui il Pantheon e Piazza di Spagna.<\/h3>\n<p class=\"withoutCaption\"><picture><source srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-1226051.webp?r=1578573618691\" type=\"image\/webp\" data-srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-1226051.webp?r=1578573618691\" \/><img decoding=\"async\" class=\"lazy loaded\" src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-1226051.jpg?r=1578573618691\" alt=\"vacanze italia roma divieto souvenir stand vacanze 2020 notizie ultime\" data-src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-1226051.jpg?r=1578573618691\" data-w=\"590\" data-h=\"350\" data-was-processed=\"true\" \/><\/picture><\/p>\n<p><span class=\"newsCaption\">Vacanze in Italia: le bancarelle possono oscurare la vista per i visitatori e aggiungere alla congestione\u00a0<span class=\"caption\">(Immagine: Getty Images)<\/span><\/span><\/p>\n<div class=\"text-description\">\n<p>Roma, in\u00a0<a href=\"https:\/\/www.express.co.uk\/latest\/italy\" target=\"_blank\" rel=\"noopener tag\" data-link-tracking=\"InArticle|Link\">Italia<\/a>\u00a0, ha vietato le bancarelle di souvenir nei luoghi turistici pi\u00f9 famosi della citt\u00e0.\u00a0Il sindaco della capitale italiana, Virginia Raggi, ha affermato che gli stand \u201coffuscano\u201d Roma.\u00a0Ha detto che le bancarelle di souvenir sono &#8220;incompatibili con il decoro e la sicurezza&#8221;.<\/p>\n<p>Raggi ha aggiunto che \u00e8 stata presa la decisione di &#8220;proteggere il patrimonio culturale e monumentale della capitale, nonch\u00e9 la sicurezza pubblica nelle aree affollate&#8221;.<\/p>\n<p>Le bancarelle, che sono spesso poste direttamente di fronte ai monumenti, possono oscurare la vista dei visitatori e accrescere la congestione intorno a quelle aree.<\/p>\n<p>Il divieto \u00e8 una mossa tanto attesa da Raggi, che in precedenza aveva rivendicato le bancarelle &#8220;rovinando l&#8217;immagine di Roma&#8221;.<\/p>\n<p>Ha detto: \u201cPer anni, i monumenti della citt\u00e0 sono stati offuscati dai venditori che vendono bevande, panini e ciondoli di fronte ai gioielli architettonici di Roma.\u00a0Questo non \u00e8 pi\u00f9 tollerabile. &#8221;<\/p>\n<p><strong>LEGGI TUTTO:\u00a0\u00a0<a href=\"https:\/\/www.express.co.uk\/travel\/articles\/1224484\/ww3-world-war-3-iran-news-safest-countries-map-holidays-2020\" target=\"_blank\" rel=\"noopener tag\" data-link-tracking=\"InArticle|Link\" data-name=\"World War Three: Safest countries in the world mapped\">Terza Guerra Mondiale: mappati i paesi pi\u00f9 sicuri del mondo<\/a>\u00a0<\/strong><\/p>\n<\/div>\n<div class=\"clear\"><\/div>\n<div class=\"photo changeSpace\">\n<p class=\"withoutCaption\"><picture><source srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249487.webp?r=1578573618782\" type=\"image\/webp\" data-srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249487.webp?r=1578573618782\" \/><img decoding=\"async\" class=\"lazy loaded\" title=\"vacanze italia roma divieto souvenir stand vacanze 2020 notizie ultime\" src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249487.jpg?r=1578573618782\" alt=\"vacanze italia roma divieto souvenir stand vacanze 2020 notizie ultime\" data-src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249487.jpg?r=1578573618782\" data-w=\"590\" data-h=\"393\" data-was-processed=\"true\" \/><\/picture><\/p>\n<p><span class=\"newsCaption\">Vacanze in Italia: il sindaco della capitale italiana, Virginia Raggi, ha affermato che gli stand \u201cappannano\u201d Roma\u00a0<span class=\"caption\">(Immagine: Getty Images)<\/span><\/span><\/p>\n<\/div>\n<div class=\"text-description\">\n<p>La repressione si applicher\u00e0 a 17 venditori a Roma che vendono souvenir come figure del Papa, magneti per il frigo e statuette del Colosseo.<\/p>\n<p>Ai venditori \u00e8 stato vietato allestire le attrazioni turistiche pi\u00f9 popolari della citt\u00e0.<\/p>\n<p>Questi siti includono Piazza di Spagna, il Pantheon, la Fontana di Trevi e Piazza Navona.<\/p>\n<div id=\"outbrain_widget_3\" class=\"OUTBRAIN\" data-src=\"https:\/\/www.express.co.uk\/travel\/articles\/1226051\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest\" data-widget-id=\"AR_2\" data-ob-template=\"Express\" data-ob-mark=\"true\" data-browser=\"chrome\" data-os=\"win32\" data-dynload=\"\" data-idx=\"3\">\n<p>Tuttavia, otto di loro saranno in grado di allestire i propri stand nelle strade vicine al sito originale.<\/p>\n<p>I venditori non sono contenti della nuova regola che reprime le bancarelle dei souvenir.<\/p>\n<p>Hanno sostenuto di fornire un servizio ai turisti a Roma.<\/p>\n<p>Angelo Di Porto, che ha una stalla accanto alla Fontana di Trevi, ha detto a The Telegraph:<\/p>\n<p>&#8220;Questo \u00e8 stato nella mia famiglia per sette generazioni.&#8221;<\/p>\n<\/div>\n<div class=\"photo changeSpace\">\n<p class=\"withoutCaption\"><picture><source srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249497.webp?r=1578573618908\" type=\"image\/webp\" data-srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249497.webp?r=1578573618908\" \/><img decoding=\"async\" class=\"lazy loaded\" title=\" vacanze italia roma divieto souvenir stand vacanze 2020 notizie ultime\" src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249497.jpg?r=1578573618908\" alt=\" vacanze italia roma divieto souvenir stand vacanze 2020 notizie ultime\" data-src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249497.jpg?r=1578573618908\" data-w=\"590\" data-h=\"384\" data-was-processed=\"true\" \/><\/picture><\/p>\n<p><span class=\"newsCaption\">Vacanze in Italia: la repressione si applicher\u00e0 a 17 venditori a Roma che vendono souvenir\u00a0<span class=\"caption\">(Immagine: Getty Images)<\/span><\/span><\/p>\n<p>Ha aggiunto che lo stand era un &#8220;business legittimo&#8221; che paga l&#8217;affitto e una serie di tasse.<\/p>\n<p>Due associazioni che rappresentano i proprietari delle bancarelle di Roma hanno promesso di combattere le nuove regole attraverso un tribunale amministrativo regionale.<\/p>\n<p>Sostengono che non sono stati offerti ai venditori abbastanza siti alternativi.<\/p>\n<p>La repressione segue una serie di misure rigorose introdotte a Roma.<\/p>\n<p>L&#8217;estate scorsa, \u00e8 stato annunciato che ai visitatori \u00e8 stato vietato di sedersi su Piazza di Spagna.<\/p>\n<p>La polizia romana emetter\u00e0 fischi a coloro che riposano i piedi e scaccia coloro che si sono alzati contro le scale.<\/p>\n<p class=\"withoutCaption\"><picture><source srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249499.webp?r=1578573618975\" type=\"image\/webp\" data-srcset=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249499.webp?r=1578573618975\" \/><img decoding=\"async\" class=\"lazy loaded\" title=\"vacanze italia roma divieto souvenir stand vacanze 2020 notizie ultime\" src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249499.jpg?r=1578573618975\" alt=\"vacanze italia roma divieto souvenir stand vacanze 2020 notizie ultime\" data-src=\"https:\/\/cdn.images.express.co.uk\/img\/dynamic\/25\/590x\/secondary\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest-2249499.jpg?r=1578573618975\" data-w=\"590\" data-h=\"393\" data-was-processed=\"true\" \/><\/picture><\/p>\n<p><span class=\"newsCaption\">Vacanze in Italia: i fornitori in questione devono spostarsi su altri siti dopo l&#8217;entrata in vigore della regola\u00a0<span class=\"caption\">(Immagine: Getty Images)<\/span><\/span><\/p>\n<\/div>\n<div class=\"text-description\">\n<p>Ora \u00e8 anche illegale trascinare valigie su ruote e passeggini lungo le scale storiche.<\/p>\n<p>Inoltre, \u00e8 vietato passeggiare per la citt\u00e0 senza una cima, cos\u00ec come entrare nelle fontane pubbliche.<\/p>\n<p>Le autorit\u00e0 di Roma hanno anche decretato che quando si beve da fontanelle pubbliche &#8211; conosciute come nasoni (che significa grandi nasi) &#8211; non \u00e8 permesso lasciare che le tue labbra tocchino il beccuccio di metallo.<\/p>\n<p>Invece, i turisti assetati dovrebbero mettere un dito sotto la bocca del becco.<\/p>\n<p>Ci\u00f2 si tradurr\u00e0 in getti d&#8217;acqua da un buco in alto e la creazione di un arco d&#8217;acqua facile da bere.<\/p>\n<p>FONTE: express.co.uk<br \/>\nhttps:\/\/www.express.co.uk\/travel\/articles\/1226051\/italy-holidays-rome-ban-souvenir-stands-holidays-2020-news-latest<\/p>\n<p><span style=\"color: #ff0000;\"><strong>ATTZ salvare da schermo le foto<\/strong><\/span><\/p>\n<\/div>\n<\/div>\n<\/header>\n","protected":false},"excerpt":{"rendered":"<p>Vacanze in Italia: Roma vieta questo nelle famose attrazioni turistiche &#8211; sei a favore o contro? ROMA, la capitale d&#8217;Italia, ha preso l&#8217;ennesima misura drastica per contenere l&#8217;eccesso di turismo nelle sue attrazioni pi\u00f9 popolari.\u00a0La citt\u00e0 ha vietato le bancarelle di souvenir nei principali siti turistici tra cui il Pantheon e Piazza di Spagna. Vacanze [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-455","post","type-post","status-publish","format-standard","hentry","category-senza-categoria"],"_links":{"self":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/comments?post=455"}],"version-history":[{"count":1,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/455\/revisions"}],"predecessor-version":[{"id":456,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/posts\/455\/revisions\/456"}],"wp:attachment":[{"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/media?parent=455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/categories?post=455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.romanews.it\/blog\/wp-json\/wp\/v2\/tags?post=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}